{"id":1480,"date":"2015-03-06T08:40:23","date_gmt":"2015-03-06T08:40:23","guid":{"rendered":"http:\/\/www.museogrigio.it\/wp\/?p=1480"},"modified":"2022-10-18T19:08:32","modified_gmt":"2022-10-18T19:08:32","slug":"i-grigi-non-superano-la-torres-ma-restano-primi","status":"publish","type":"post","link":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/","title":{"rendered":"I Grigi non superano la Torres ma restano primi"},"content":{"rendered":"<p><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1482\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2.jpg\" alt=\"Alessandria-Torres 04_03_2015 (2)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>L\u2019<strong>Alessandria<\/strong> per continuare la marcia in classifica, la <strong>Torres<\/strong> per riscattare l\u2019opaca prova contro la <strong>Giana Erminio<\/strong> e tenere lontana la zona play out: i presupposti per assistere a una partita gradevole c\u2019erano tutti, ma <strong>le due squadre hanno, in parte, tradito le attese<\/strong> e hanno dato vita a una contesa povera di contenuti tecnici, che si \u00e8 conclusa con una spartizione della posta in palio, decisamente pi\u00f9 gratificante per i ragazzi di <strong>Mister Bucchi<\/strong>, anche se i <strong>Grigi conservano il primato<\/strong>, in coabitazione col <strong>Pavia<\/strong>, grazie al<strong> capitombolo del Novara sul campo del Como<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-21.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1483\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-21.jpg\" alt=\"Alessandria-Torres 04_03_2015 (21)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-21.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-21-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-21-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>Le due reti, che hanno fissato <strong>l\u20191 a 1 finale<\/strong>, sono state realizzate nella parte iniziale della gara: al 6\u2032 <strong>Cerone<\/strong> (<strong>ex grigio con Vatta e Milani<\/strong>) ha sbloccato il risultato, <strong>trasformando un rigore<\/strong> concesso per un <strong>fallo di Nordi su Baraye, lanciato da Petermann<\/strong>.<br \/>\nSubito il contraccolpo psicologico, i padroni di casa hanno tardato a reagire, ma <strong>hanno trovato il jolly, al 18\u2032, con una giocata personale di Iunco<\/strong>, abile a controllare un pallone al limite dell\u2019area, girarsi e trafiggere <strong>Testa<\/strong>, apparso non esente da colpe nell\u2019occasione, con un destro potente e fulminante.<\/p>\n<p><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1484\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-15.jpg\" alt=\"Alessandria-Torres 04_03_2015 (15)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-15.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-15-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-15-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>Da quel momento in poi, i rossobl\u00f9 hanno badato soprattutto a contenere le iniziative degli avversari che, prima dell\u2019intervallo, si sono resi pericolosi con <strong>due conclusioni di Vitofrancesco<\/strong>.<br \/>\nIl copione della gara non \u00e8 cambiato nella ripresa, caratterizzata da una, seppur sterile, <strong>supremazia territoriale dei Grigi<\/strong>, i quali hanno sfiorato la segnatura, <strong>al 63\u2032, con Valentini, la cui conclusione da posizione favorevole \u00e8 stata respinta da Testa<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" title=\"M4H05150 - Alessandria - Torres (1 a 1) - Il gol dei Grigi\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/WHCsfcuxO24?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><strong><em>Il gol di Iunco visto dalla Curva Nord.<\/em><\/strong><\/p>\n<p>Nei minuti finali, una conclusione di <strong>Mezzavilla<\/strong> e una deviazione goffa di <strong>Cerone<\/strong> hanno fatto gridare al gol <strong>il pubblico della \u201cNord\u201d<\/strong>. Il risultato \u00e8 rimasto invariato fino al termine della contesa e la <strong>Torres<\/strong> ha lasciato il <strong>Moccagatta<\/strong>, campo in cui ha scritto una delle pagine pi\u00f9 belle della sua storia, con un punto tutto sommato meritato.<br \/>\nPer la sfida a <strong>Pordenone<\/strong> l\u2019emergenza \u00e8 aumentata: <strong>Marconi<\/strong> si \u00e8 fermato toccandosi l&#8217;interno coscia, sintomo un problema muscolare, mentre <strong>Germinale<\/strong> ammonito sar\u00e0 squalificato (era in diffida). Di positivo ci sar\u00e0 il rientro di<strong> Rantier<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1485\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-1.jpg\" alt=\"Alessandria-Torres 04_03_2015 (1)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-1.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-1-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-1-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><strong>In sala stampa<\/strong><\/p>\n<p>Cos\u00ec <strong>Mister D&#8217;Angelo<\/strong>: <em>\u201cAvremmo meritato la vittoria. <strong>\u00c8 comunque un punto molto importante, la Torres si \u00e8 solo difesa.<\/strong> Comunque ho fiducia nella rosa, questo \u00e8 un gruppo importante e q<strong>uesta sera siamo primi in classifica<\/strong>: nelle prossime dieci domeniche daremo battaglia\u201d.<\/em><br \/>\n<strong>Guazzo reintegrato?<\/strong> Ancora D&#8217;Angelo:<em> &#8220;<strong>E&#8217; una decisione del presidente<\/strong>, lui solo pu\u00f2 rispondere. Matteo ed io ci siamo chiariti&#8221;<\/em>.<\/p>\n<p><strong>Valentini<\/strong> sulla sua ghiotta occasione da rete: <em>&#8220;Pensavo che il portiere uscisse a valanga&#8221;<\/em>.<\/p>\n<p><strong>Sosa:<\/strong> <em>&#8220;Il rigore si pu\u00f2 anche dare, per\u00f2 <strong>dobbiamo eliminare gli errori nelle azioni di ripartenza<\/strong> degli avversari\u201d.<\/em><\/p>\n<p>Successivamente alla partita \u00e8 giunta la dichiarazione del <strong>presidente Luca Di Masi<\/strong>: <em>\u201cReintegrare <strong>Guazzo<\/strong>? No, <strong>non fa parte del progetto tecnico<\/strong>. Non cambio solo perch\u00e9 possiamo avere qualche defezione\u201d<\/em><\/p>\n<p style=\"text-align: right;\"><em><strong>Mario Bocchio<\/strong><\/em><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-22.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1486\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-22.jpg\" alt=\"Alessandria-Torres 04_03_2015 (22)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-22.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-22-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-22-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><strong>IL TABELLINO &#8211; Alessandria:<\/strong> Nordi, Sosa, Sabato, Morero, Mezavilla, Nicolao (dal 79\u2032 Terigi), Vitofrancesco, Obodo, Marconi (dal 22\u2032 Germinale), Valentini (C), Iunco.<br \/>\nA disposizione: Poluzzi, Terigi, Germinale, Picone, Gentile, Casula, Zarmanian. All. Luca D\u2019Angelo.<\/p>\n<p><strong>Torres:<\/strong> Testa, Aya, Ligorio (dal 55\u2032 Foglia), Cerone, Marchetti, Migliaccio, Imparato, Petermann, Scotto, Marinaro, Baraye.<br \/>\nA disposizione: Costantino, Schiavino, Bottone, Foglia, Buonaiuto, Maiorino, Colombi. All. Cristian Bucchi.<\/p>\n<p><strong>Arbitro:<\/strong> Saverio Pelagatti di Arezzo.<\/p>\n<p><strong>Reti:<\/strong> 6\u2032 Cerone (T, rig.), 17\u2032 Iunco (A).<\/p>\n<p><strong>Ammoniti:<\/strong> 5\u2032 Nordi (A), 15\u2032 Cerone (T), 65\u2032 Obodo (A), 87\u2032 Iunco(A), 78\u2032 Germinale (A), 82\u2032 Picone (A).<\/p>\n<p><strong>Calci d\u2019angolo:<\/strong> 4-3.<\/p>\n<p><strong>Recupero:<\/strong> 2 minuti nel primo tempo; 5 minuti nel secondo tempo.<\/p>\n<p><a href=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1489\" src=\"http:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-5.jpg\" alt=\"Alessandria-Torres 04_03_2015 (5)\" width=\"960\" height=\"652\" srcset=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-5.jpg 960w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-5-300x203.jpg 300w, https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-5-624x423.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.datasport.it\/calcio\/2014-2015\/lega-pro\/girone-a\/classifica.htm?idediz=15520&amp;giornata=31\">Tutti i risultati, la classifica e il calendario del girone A della Lega Pro: cliccare qui<\/a><\/p>\n<p><em>Le fotografie sono tratte dal profilo Facebook dell&#8217;Alessandria Calcio e sono di Mauro Zoboli.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Alessandria per continuare la marcia in classifica, la Torres per riscattare l\u2019opaca prova contro la Giana Erminio e tenere lontana la zona play out: i presupposti per assistere a una partita gradevole c\u2019erano tutti, ma le due squadre hanno, in parte, tradito le attese e hanno dato vita a una contesa povera di contenuti tecnici, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I Grigi non superano la Torres ma restano primi - Museo Grigio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I Grigi non superano la Torres ma restano primi - Museo Grigio\" \/>\n<meta property=\"og:description\" content=\"L\u2019Alessandria per continuare la marcia in classifica, la Torres per riscattare l\u2019opaca prova contro la Giana Erminio e tenere lontana la zona play out: i presupposti per assistere a una partita gradevole c\u2019erano tutti, ma le due squadre hanno, in parte, tradito le attese e hanno dato vita a una contesa povera di contenuti tecnici, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo Grigio\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-06T08:40:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-18T19:08:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mgblogger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mgblogger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/\"},\"author\":{\"name\":\"mgblogger\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/#\\\/schema\\\/person\\\/7ae7f5a79c8f571fd56d74aabb80b3f3\"},\"headline\":\"I Grigi non superano la Torres ma restano primi\",\"datePublished\":\"2015-03-06T08:40:23+00:00\",\"dateModified\":\"2022-10-18T19:08:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/\"},\"wordCount\":623,\"image\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Alessandria-Torres-04_03_2015-2-1.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/\",\"url\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/\",\"name\":\"I Grigi non superano la Torres ma restano primi - Museo Grigio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Alessandria-Torres-04_03_2015-2-1.jpg\",\"datePublished\":\"2015-03-06T08:40:23+00:00\",\"dateModified\":\"2022-10-18T19:08:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/#\\\/schema\\\/person\\\/7ae7f5a79c8f571fd56d74aabb80b3f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Alessandria-Torres-04_03_2015-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Alessandria-Torres-04_03_2015-2-1.jpg\",\"width\":960,\"height\":652},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/i-grigi-non-superano-la-torres-ma-restano-primi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I Grigi non superano la Torres ma restano primi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/\",\"name\":\"Museo Grigio\",\"description\":\"Museo Grigio Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/#\\\/schema\\\/person\\\/7ae7f5a79c8f571fd56d74aabb80b3f3\",\"name\":\"mgblogger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g\",\"caption\":\"mgblogger\"},\"url\":\"https:\\\/\\\/www.museogrigio.it\\\/wp\\\/author\\\/mgblogger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I Grigi non superano la Torres ma restano primi - Museo Grigio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/","og_locale":"it_IT","og_type":"article","og_title":"I Grigi non superano la Torres ma restano primi - Museo Grigio","og_description":"L\u2019Alessandria per continuare la marcia in classifica, la Torres per riscattare l\u2019opaca prova contro la Giana Erminio e tenere lontana la zona play out: i presupposti per assistere a una partita gradevole c\u2019erano tutti, ma le due squadre hanno, in parte, tradito le attese e hanno dato vita a una contesa povera di contenuti tecnici, [&hellip;]","og_url":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/","og_site_name":"Museo Grigio","article_published_time":"2015-03-06T08:40:23+00:00","article_modified_time":"2022-10-18T19:08:32+00:00","og_image":[{"width":960,"height":652,"url":"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg","type":"image\/jpeg"}],"author":"mgblogger","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"mgblogger","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#article","isPartOf":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/"},"author":{"name":"mgblogger","@id":"https:\/\/www.museogrigio.it\/wp\/#\/schema\/person\/7ae7f5a79c8f571fd56d74aabb80b3f3"},"headline":"I Grigi non superano la Torres ma restano primi","datePublished":"2015-03-06T08:40:23+00:00","dateModified":"2022-10-18T19:08:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/"},"wordCount":623,"image":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/","url":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/","name":"I Grigi non superano la Torres ma restano primi - Museo Grigio","isPartOf":{"@id":"https:\/\/www.museogrigio.it\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#primaryimage"},"image":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg","datePublished":"2015-03-06T08:40:23+00:00","dateModified":"2022-10-18T19:08:32+00:00","author":{"@id":"https:\/\/www.museogrigio.it\/wp\/#\/schema\/person\/7ae7f5a79c8f571fd56d74aabb80b3f3"},"breadcrumb":{"@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#primaryimage","url":"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg","contentUrl":"https:\/\/www.museogrigio.it\/wp\/wp-content\/uploads\/2015\/03\/Alessandria-Torres-04_03_2015-2-1.jpg","width":960,"height":652},{"@type":"BreadcrumbList","@id":"https:\/\/www.museogrigio.it\/wp\/i-grigi-non-superano-la-torres-ma-restano-primi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.museogrigio.it\/wp\/"},{"@type":"ListItem","position":2,"name":"I Grigi non superano la Torres ma restano primi"}]},{"@type":"WebSite","@id":"https:\/\/www.museogrigio.it\/wp\/#website","url":"https:\/\/www.museogrigio.it\/wp\/","name":"Museo Grigio","description":"Museo Grigio Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museogrigio.it\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.museogrigio.it\/wp\/#\/schema\/person\/7ae7f5a79c8f571fd56d74aabb80b3f3","name":"mgblogger","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c01466dbaec6f151089fefd81e4e31df853c7b5c4af467acdacd2bda7e1e497a?s=96&d=mm&r=g","caption":"mgblogger"},"url":"https:\/\/www.museogrigio.it\/wp\/author\/mgblogger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/posts\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/comments?post=1480"}],"version-history":[{"count":7,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/posts\/1480\/revisions"}],"predecessor-version":[{"id":47542,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/posts\/1480\/revisions\/47542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/media\/47541"}],"wp:attachment":[{"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/media?parent=1480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/categories?post=1480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.museogrigio.it\/wp\/wp-json\/wp\/v2\/tags?post=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}